{"id":4160,"date":"2025-09-11T07:40:06","date_gmt":"2025-09-11T07:40:06","guid":{"rendered":"https:\/\/prio.swiss\/?p=4160"},"modified":"2025-09-11T07:40:06","modified_gmt":"2025-09-11T07:40:06","slug":"deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation","status":"publish","type":"post","link":"https:\/\/prio.swiss\/fr\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\/","title":{"rendered":"Deux conventions qualit\u00e9, pour les cabinets m\u00e9dicaux et les conseils di\u00e9t\u00e9tiques et nutritionnels, ont \u00e9t\u00e9 remises au Conseil f\u00e9d\u00e9ral pour approbation"},"content":{"rendered":"<p><strong>11.9.2025<\/strong><\/p>\n<p><strong>L\u2019association des assureurs-maladie suisses (prio.swiss), la F\u00e9d\u00e9ration des m\u00e9decins suisses (FMH) et l\u2019Association suisse des di\u00e9t\u00e9ticien-ne-s (ASDD) ont remis aujourd\u2019hui au Conseil f\u00e9d\u00e9ral les deux premi\u00e8res conventions qualit\u00e9 nationales pour le secteur ambulatoire. La premi\u00e8re concerne les cabinets m\u00e9dicaux et a \u00e9t\u00e9 n\u00e9goci\u00e9e entre prio.swiss et la FMH. La seconde, conclue entre prio.swiss et l\u2019ASDD, porte sur les conseils di\u00e9t\u00e9tiques et nutritionnels. Les partenaires tarifaires mettent ainsi en application l\u2019article de loi visant \u00e0 renforcer la qualit\u00e9 et l\u2019\u00e9conomicit\u00e9 (art. 58a LAMal) et cr\u00e9ent une base obligatoire pour le d\u00e9veloppement continu de la qualit\u00e9 dans le syst\u00e8me de sant\u00e9. <\/strong><\/p>\n<p>Les conventions qualit\u00e9 remises aujourd\u2019hui au Conseil f\u00e9d\u00e9ral sont le r\u00e9sultat de n\u00e9gociations intensives et constructives, entre prio.swiss et la FMH d\u2019une part, et entre prio.swiss et l\u2019ASDD d\u2019autre part. Elles d\u00e9finissent de mani\u00e8re contraignante la collaboration pour un d\u00e9veloppement syst\u00e9matique et durable de la qualit\u00e9 des prestations ambulatoires en pratique priv\u00e9e. Les patientes et les patients b\u00e9n\u00e9ficient ainsi de mesures d\u2019am\u00e9lioration efficaces.<\/p>\n<p>L\u2019accent est mis sur la promotion d\u2019une culture de la qualit\u00e9 et de l\u2019apprentissage. Les conventions qualit\u00e9 contribuent \u00e0 un traitement s\u00fbr, fond\u00e9 sur les preuves et centr\u00e9 sur les patients, et pr\u00e9voient des mesures sp\u00e9cifiques d\u2019am\u00e9lioration de la qualit\u00e9. La convention qualit\u00e9 pour les cabinets m\u00e9dicaux pr\u00e9voit par exemple une check-list sur la s\u00e9curit\u00e9 en chirurgie et des cercles de qualit\u00e9, tandis que celle \u00e9tablie pour les di\u00e9t\u00e9ticiennes et di\u00e9t\u00e9ticiens en pratique priv\u00e9e met en avant la mesure de la satisfaction des patients. La qualit\u00e9 r\u00e9sulte d\u2019un d\u00e9veloppement continu, c\u2019est pourquoi la mise en \u0153uvre sera r\u00e9guli\u00e8rement pass\u00e9e en revue par les partenaires conventionnels et adapt\u00e9e si n\u00e9cessaire.<\/p>\n<p>Pour Yvonne Gilli, pr\u00e9sidente de la FMH\u00a0: \u00ab\u00a0Cette convention marque une \u00e9tape importante dans la d\u00e9marche qualit\u00e9 des m\u00e9decins. Elle associe les perspectives du corps m\u00e9dical et des assureurs et met l\u2019accent sur le b\u00e9n\u00e9fice pour les patientes et les patients.\u00a0\u00bb Felix Gutzwiller, pr\u00e9sident de prio.swiss, ajoute\u00a0: \u00ab\u00a0Avec cette convention, nous avons cr\u00e9\u00e9 un cadre fiable pour concilier qualit\u00e9 et \u00e9conomicit\u00e9. Cela renforce non seulement le syst\u00e8me de sant\u00e9, mais aussi et surtout la confiance de la population.\u00a0\u00bb Manuela Deiss, vice-pr\u00e9sidente de l\u2019ASDD, abonde dans ce sens\u00a0: \u00ab\u00a0Ces nouvelles conventions r\u00e9pondent aux diff\u00e9rents besoins des patientes et des patients. Elles garantissent ainsi une efficacit\u00e9 optimale du d\u00e9veloppement de la qualit\u00e9.\u00a0\u00bb<\/p>\n<p><strong>Renseignements <\/strong><\/p>\n<p>Adrien Kay, responsable de la communication, prio.swiss, 079\u00a0154\u00a063\u00a000, <a href=\"mailto:media@prio.swiss\">media@prio.swiss<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019association des assureurs-maladie suisses (prio.swiss), la F\u00e9d\u00e9ration des m\u00e9decins suisses (FMH) et l\u2019Association suisse des di\u00e9t\u00e9ticien-ne-s (ASDD) ont remis aujourd\u2019hui au Conseil f\u00e9d\u00e9ral les deux premi\u00e8res conventions qualit\u00e9 nationales pour le secteur ambulatoire. La premi\u00e8re concerne les cabinets m\u00e9dicaux et a \u00e9t\u00e9 n\u00e9goci\u00e9e entre prio.swiss et la FMH. La seconde, conclue entre prio.swiss et l\u2019ASDD, porte sur les conseils di\u00e9t\u00e9tiques et nutritionnels. Les partenaires tarifaires mettent ainsi en application l\u2019article de loi visant \u00e0 renforcer la qualit\u00e9 et l\u2019\u00e9conomicit\u00e9 (art. 58a LAMal) et cr\u00e9ent une base obligatoire pour le d\u00e9veloppement continu de la qualit\u00e9 dans le syst\u00e8me de sant\u00e9. <\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[26],"tags":[],"class_list":["post-4160","post","type-post","status-publish","format-standard","hentry","category-communiques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Deux conventions qualit\u00e9, pour les cabinets m\u00e9dicaux et les conseils di\u00e9t\u00e9tiques et nutritionnels, ont \u00e9t\u00e9 remises au Conseil f\u00e9d\u00e9ral pour approbation - Prio.Swiss \u2013 Der Verband Schweizer Krankenversicherer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prio.swiss\/fr\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deux conventions qualit\u00e9, pour les cabinets m\u00e9dicaux et les conseils di\u00e9t\u00e9tiques et nutritionnels, ont \u00e9t\u00e9 remises au Conseil f\u00e9d\u00e9ral pour approbation - Prio.Swiss \u2013 Der Verband Schweizer Krankenversicherer\" \/>\n<meta property=\"og:description\" content=\"L\u2019association des assureurs-maladie suisses (prio.swiss), la F\u00e9d\u00e9ration des m\u00e9decins suisses (FMH) et l\u2019Association suisse des di\u00e9t\u00e9ticien-ne-s (ASDD) ont remis aujourd\u2019hui au Conseil f\u00e9d\u00e9ral les deux premi\u00e8res conventions qualit\u00e9 nationales pour le secteur ambulatoire. La premi\u00e8re concerne les cabinets m\u00e9dicaux et a \u00e9t\u00e9 n\u00e9goci\u00e9e entre prio.swiss et la FMH. La seconde, conclue entre prio.swiss et l\u2019ASDD, porte sur les conseils di\u00e9t\u00e9tiques et nutritionnels. Les partenaires tarifaires mettent ainsi en application l\u2019article de loi visant \u00e0 renforcer la qualit\u00e9 et l\u2019\u00e9conomicit\u00e9 (art. 58a LAMal) et cr\u00e9ent une base obligatoire pour le d\u00e9veloppement continu de la qualit\u00e9 dans le syst\u00e8me de sant\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prio.swiss\/fr\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\/\" \/>\n<meta property=\"og:site_name\" content=\"Prio.Swiss \u2013 Der Verband Schweizer Krankenversicherer\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-11T07:40:06+00:00\" \/>\n<meta name=\"author\" content=\"Ivo Giudicetti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ivo Giudicetti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prio.swiss\\\/fr\\\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prio.swiss\\\/fr\\\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\\\/\"},\"author\":{\"name\":\"Ivo Giudicetti\",\"@id\":\"https:\\\/\\\/prio.swiss\\\/#\\\/schema\\\/person\\\/4d9497c27b718f03a1e874527475adea\"},\"headline\":\"Deux conventions qualit\u00e9, pour les cabinets m\u00e9dicaux et les conseils di\u00e9t\u00e9tiques et nutritionnels, ont \u00e9t\u00e9 remises au Conseil f\u00e9d\u00e9ral pour approbation\",\"datePublished\":\"2025-09-11T07:40:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prio.swiss\\\/fr\\\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\\\/\"},\"wordCount\":503,\"articleSection\":[\"Communiqu\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prio.swiss\\\/fr\\\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\\\/\",\"url\":\"https:\\\/\\\/prio.swiss\\\/fr\\\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\\\/\",\"name\":\"Deux conventions qualit\u00e9, pour les cabinets m\u00e9dicaux et les conseils di\u00e9t\u00e9tiques et nutritionnels, ont \u00e9t\u00e9 remises au Conseil f\u00e9d\u00e9ral pour approbation - Prio.Swiss \u2013 Der Verband Schweizer Krankenversicherer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prio.swiss\\\/#website\"},\"datePublished\":\"2025-09-11T07:40:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/prio.swiss\\\/#\\\/schema\\\/person\\\/4d9497c27b718f03a1e874527475adea\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prio.swiss\\\/fr\\\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prio.swiss\\\/fr\\\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prio.swiss\\\/fr\\\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/prio.swiss\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deux conventions qualit\u00e9, pour les cabinets m\u00e9dicaux et les conseils di\u00e9t\u00e9tiques et nutritionnels, ont \u00e9t\u00e9 remises au Conseil f\u00e9d\u00e9ral pour approbation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prio.swiss\\\/#website\",\"url\":\"https:\\\/\\\/prio.swiss\\\/\",\"name\":\"Prio.Swiss \u2013 Der Verband Schweizer Krankenversicherer\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prio.swiss\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prio.swiss\\\/#\\\/schema\\\/person\\\/4d9497c27b718f03a1e874527475adea\",\"name\":\"Ivo Giudicetti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9556a66894283924e2a939c86ab0cdd52d95066a830df044151992e554b0577?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9556a66894283924e2a939c86ab0cdd52d95066a830df044151992e554b0577?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9556a66894283924e2a939c86ab0cdd52d95066a830df044151992e554b0577?s=96&d=mm&r=g\",\"caption\":\"Ivo Giudicetti\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deux conventions qualit\u00e9, pour les cabinets m\u00e9dicaux et les conseils di\u00e9t\u00e9tiques et nutritionnels, ont \u00e9t\u00e9 remises au Conseil f\u00e9d\u00e9ral pour approbation - Prio.Swiss \u2013 Der Verband Schweizer Krankenversicherer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prio.swiss\/fr\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\/","og_locale":"fr_FR","og_type":"article","og_title":"Deux conventions qualit\u00e9, pour les cabinets m\u00e9dicaux et les conseils di\u00e9t\u00e9tiques et nutritionnels, ont \u00e9t\u00e9 remises au Conseil f\u00e9d\u00e9ral pour approbation - Prio.Swiss \u2013 Der Verband Schweizer Krankenversicherer","og_description":"L\u2019association des assureurs-maladie suisses (prio.swiss), la F\u00e9d\u00e9ration des m\u00e9decins suisses (FMH) et l\u2019Association suisse des di\u00e9t\u00e9ticien-ne-s (ASDD) ont remis aujourd\u2019hui au Conseil f\u00e9d\u00e9ral les deux premi\u00e8res conventions qualit\u00e9 nationales pour le secteur ambulatoire. La premi\u00e8re concerne les cabinets m\u00e9dicaux et a \u00e9t\u00e9 n\u00e9goci\u00e9e entre prio.swiss et la FMH. La seconde, conclue entre prio.swiss et l\u2019ASDD, porte sur les conseils di\u00e9t\u00e9tiques et nutritionnels. Les partenaires tarifaires mettent ainsi en application l\u2019article de loi visant \u00e0 renforcer la qualit\u00e9 et l\u2019\u00e9conomicit\u00e9 (art. 58a LAMal) et cr\u00e9ent une base obligatoire pour le d\u00e9veloppement continu de la qualit\u00e9 dans le syst\u00e8me de sant\u00e9.","og_url":"https:\/\/prio.swiss\/fr\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\/","og_site_name":"Prio.Swiss \u2013 Der Verband Schweizer Krankenversicherer","article_published_time":"2025-09-11T07:40:06+00:00","author":"Ivo Giudicetti","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ivo Giudicetti","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prio.swiss\/fr\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\/#article","isPartOf":{"@id":"https:\/\/prio.swiss\/fr\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\/"},"author":{"name":"Ivo Giudicetti","@id":"https:\/\/prio.swiss\/#\/schema\/person\/4d9497c27b718f03a1e874527475adea"},"headline":"Deux conventions qualit\u00e9, pour les cabinets m\u00e9dicaux et les conseils di\u00e9t\u00e9tiques et nutritionnels, ont \u00e9t\u00e9 remises au Conseil f\u00e9d\u00e9ral pour approbation","datePublished":"2025-09-11T07:40:06+00:00","mainEntityOfPage":{"@id":"https:\/\/prio.swiss\/fr\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\/"},"wordCount":503,"articleSection":["Communiqu\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/prio.swiss\/fr\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\/","url":"https:\/\/prio.swiss\/fr\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\/","name":"Deux conventions qualit\u00e9, pour les cabinets m\u00e9dicaux et les conseils di\u00e9t\u00e9tiques et nutritionnels, ont \u00e9t\u00e9 remises au Conseil f\u00e9d\u00e9ral pour approbation - Prio.Swiss \u2013 Der Verband Schweizer Krankenversicherer","isPartOf":{"@id":"https:\/\/prio.swiss\/#website"},"datePublished":"2025-09-11T07:40:06+00:00","author":{"@id":"https:\/\/prio.swiss\/#\/schema\/person\/4d9497c27b718f03a1e874527475adea"},"breadcrumb":{"@id":"https:\/\/prio.swiss\/fr\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prio.swiss\/fr\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/prio.swiss\/fr\/deux-conventions-qualite-pour-les-cabinets-medicaux-et-les-conseils-dietetiques-et-nutritionnels-ont-ete-remises-au-conseil-federal-pour-approbation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/prio.swiss\/fr\/"},{"@type":"ListItem","position":2,"name":"Deux conventions qualit\u00e9, pour les cabinets m\u00e9dicaux et les conseils di\u00e9t\u00e9tiques et nutritionnels, ont \u00e9t\u00e9 remises au Conseil f\u00e9d\u00e9ral pour approbation"}]},{"@type":"WebSite","@id":"https:\/\/prio.swiss\/#website","url":"https:\/\/prio.swiss\/","name":"Prio.Swiss \u2013 Der Verband Schweizer Krankenversicherer","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prio.swiss\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/prio.swiss\/#\/schema\/person\/4d9497c27b718f03a1e874527475adea","name":"Ivo Giudicetti","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a9556a66894283924e2a939c86ab0cdd52d95066a830df044151992e554b0577?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a9556a66894283924e2a939c86ab0cdd52d95066a830df044151992e554b0577?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a9556a66894283924e2a939c86ab0cdd52d95066a830df044151992e554b0577?s=96&d=mm&r=g","caption":"Ivo Giudicetti"}}]}},"_links":{"self":[{"href":"https:\/\/prio.swiss\/fr\/wp-json\/wp\/v2\/posts\/4160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prio.swiss\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prio.swiss\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prio.swiss\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/prio.swiss\/fr\/wp-json\/wp\/v2\/comments?post=4160"}],"version-history":[{"count":7,"href":"https:\/\/prio.swiss\/fr\/wp-json\/wp\/v2\/posts\/4160\/revisions"}],"predecessor-version":[{"id":4168,"href":"https:\/\/prio.swiss\/fr\/wp-json\/wp\/v2\/posts\/4160\/revisions\/4168"}],"wp:attachment":[{"href":"https:\/\/prio.swiss\/fr\/wp-json\/wp\/v2\/media?parent=4160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prio.swiss\/fr\/wp-json\/wp\/v2\/categories?post=4160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prio.swiss\/fr\/wp-json\/wp\/v2\/tags?post=4160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}