{"id":4837,"date":"2025-11-27T13:09:16","date_gmt":"2025-11-27T13:09:16","guid":{"rendered":"https:\/\/prio.swiss\/?p=4837"},"modified":"2025-11-28T08:21:16","modified_gmt":"2025-11-28T08:21:16","slug":"trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia","status":"publish","type":"post","link":"https:\/\/prio.swiss\/it\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\/","title":{"rendered":"Trasmessa al Consiglio federale la convenzione sulla qualit\u00e0 per l\u2019ergoterapia"},"content":{"rendered":"<p>Berna, 27 novembre 2025<\/p>\n<p><strong>L\u2019Associazione svizzera di ergoterapia, la Croce Rossa Svizzera e l\u2019Associazione degli assicuratori-malattia svizzeri prio.swiss hanno presentato oggi al Consiglio federale la convenzione sulla qualit\u00e0 tra ergoterapisti e assicuratori malattia. La convenzione \u00e8 stata aggiornata e adeguata alle nuove disposizioni sul rafforzamento della qualit\u00e0 e dell\u2019economicit\u00e0 (art. 58a LAMal) e crea una base vincolante per lo sviluppo costante della qualit\u00e0 nel settore dell\u2019ergoterapia ambulatoriale.<\/strong><\/p>\n<p>La convenzione sulla qualit\u00e0 presentata oggi al Consiglio federale e i relativi allegati sono il frutto di intensi e costruttivi negoziati tra prio.swiss, l\u2019Associazione svizzera di ergoterapia (ASE) e la Croce Rossa Svizzera (CRS). La convenzione fissa in modo vincolante la collaborazione per uno sviluppo della qualit\u00e0 sistematico e sostenibile nell\u2019assistenza sanitaria ambulatoriale e porter\u00e0 benefici ai pazienti grazie a misure di miglioramento efficaci.<\/p>\n<p><strong>Valutazione degli obiettivi terapeutici e circoli di qualit\u00e0<\/strong><\/p>\n<p>Un punto fondamentale della convenzione riguarda le misurazioni specifiche per la definizione congiunta degli obiettivi terapeutici tra ergoterapisti e pazienti. I circoli di qualit\u00e0 e i colloqui collegiali sulla qualit\u00e0 sono i principali strumenti del processo di miglioramento continuo: permettono agli ergoterapisti di scambiarsi informazioni in modo strutturato su importanti questioni che concernono la qualit\u00e0 e di identificare insieme il potenziale di miglioramento. Le misure di miglioramento individuate sono poi accettate dai partner contrattuali come parte integrante della convenzione e vengono successivamente implementate dai fornitori di prestazioni nei loro studi e ambulatori.<\/p>\n<p><strong>Processo continuo di sviluppo della qualit\u00e0<\/strong><\/p>\n<p>Felix Gutzwiller, presidente di prio.swiss, \u00e8 soddisfatto: \u00abCon la nuova convenzione sulla qualit\u00e0 siamo riusciti, partendo dalla collaborazione collaudata con i nostri partner, ad attuare i nuovi requisiti di qualit\u00e0 previsti dalla legge e a creare un processo continuo di sviluppo della qualit\u00e0\u00bb.<\/p>\n<p>Colette Carroz, presidente dell\u2019ASE, sottolinea: \u00abLa convenzione sulla qualit\u00e0 2025 sostituisce quella del 2009. Non \u00e8 cambiata solo la data. Si tratta anche e soprattutto di un miglioramento dei requisiti di qualit\u00e0 nel settore dell\u2019ergoterapia\u00bb.<\/p>\n<p>Sarah Kopse, vicedirettrice della CRS, aggiunge: \u00abLa nuova convenzione promuove gli sforzi congiunti per la garanzia e lo sviluppo della qualit\u00e0. \u00c8 un passo importante per rispondere sempre meglio ai bisogni dei pazienti\u00bb.<\/p>\n<p><strong>Contatto <\/strong><\/p>\n<p>Colette Carroz, presidente ASE, +41 31 313 88 44, <a href=\"mailto:colette.carroz@ergotherapie.ch\">colette.carroz@ergotherapie.ch<\/a><\/p>\n<p>Jo\u00eblle Etienne, portavoce CRS, +41 58 400 44 13, <a href=\"mailto:joelle.etienne@redcross.ch\u00d6ffnet%20ein%20neues%20Fenster\">joelle.etienne@redcross.ch<\/a><\/p>\n<p>Ivo Giudicetti, portavoce prio.swiss, +41 79 123 84 42, <a href=\"mailto:media@prio.swiss\">media@prio.swiss<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Associazione svizzera di ergoterapia, la Croce Rossa Svizzera e l\u2019Associazione degli assicuratori-malattia svizzeri prio.swiss hanno presentato oggi al Consiglio federale la convenzione sulla qualit\u00e0 tra ergoterapisti e assicuratori malattia.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[27],"tags":[],"class_list":["post-4837","post","type-post","status-publish","format-standard","hentry","category-comunicati"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trasmessa al Consiglio federale la convenzione sulla qualit\u00e0 per l\u2019ergoterapia - Prio.Swiss \u2013 Der Verband Schweizer Krankenversicherer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prio.swiss\/it\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trasmessa al Consiglio federale la convenzione sulla qualit\u00e0 per l\u2019ergoterapia - Prio.Swiss \u2013 Der Verband Schweizer Krankenversicherer\" \/>\n<meta property=\"og:description\" content=\"L\u2019Associazione svizzera di ergoterapia, la Croce Rossa Svizzera e l\u2019Associazione degli assicuratori-malattia svizzeri prio.swiss hanno presentato oggi al Consiglio federale la convenzione sulla qualit\u00e0 tra ergoterapisti e assicuratori malattia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prio.swiss\/it\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\/\" \/>\n<meta property=\"og:site_name\" content=\"Prio.Swiss \u2013 Der Verband Schweizer Krankenversicherer\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-27T13:09:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-28T08:21:16+00:00\" \/>\n<meta name=\"author\" content=\"Ivo Giudicetti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ivo Giudicetti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prio.swiss\\\/it\\\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prio.swiss\\\/it\\\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\\\/\"},\"author\":{\"name\":\"Ivo Giudicetti\",\"@id\":\"https:\\\/\\\/prio.swiss\\\/#\\\/schema\\\/person\\\/4d9497c27b718f03a1e874527475adea\"},\"headline\":\"Trasmessa al Consiglio federale la convenzione sulla qualit\u00e0 per l\u2019ergoterapia\",\"datePublished\":\"2025-11-27T13:09:16+00:00\",\"dateModified\":\"2025-11-28T08:21:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prio.swiss\\\/it\\\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\\\/\"},\"wordCount\":388,\"articleSection\":[\"Comunicati\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prio.swiss\\\/it\\\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\\\/\",\"url\":\"https:\\\/\\\/prio.swiss\\\/it\\\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\\\/\",\"name\":\"Trasmessa al Consiglio federale la convenzione sulla qualit\u00e0 per l\u2019ergoterapia - Prio.Swiss \u2013 Der Verband Schweizer Krankenversicherer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prio.swiss\\\/#website\"},\"datePublished\":\"2025-11-27T13:09:16+00:00\",\"dateModified\":\"2025-11-28T08:21:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/prio.swiss\\\/#\\\/schema\\\/person\\\/4d9497c27b718f03a1e874527475adea\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prio.swiss\\\/it\\\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prio.swiss\\\/it\\\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prio.swiss\\\/it\\\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/prio.swiss\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trasmessa al Consiglio federale la convenzione sulla qualit\u00e0 per l\u2019ergoterapia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prio.swiss\\\/#website\",\"url\":\"https:\\\/\\\/prio.swiss\\\/\",\"name\":\"Prio.Swiss \u2013 Der Verband Schweizer Krankenversicherer\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prio.swiss\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prio.swiss\\\/#\\\/schema\\\/person\\\/4d9497c27b718f03a1e874527475adea\",\"name\":\"Ivo Giudicetti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9556a66894283924e2a939c86ab0cdd52d95066a830df044151992e554b0577?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9556a66894283924e2a939c86ab0cdd52d95066a830df044151992e554b0577?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9556a66894283924e2a939c86ab0cdd52d95066a830df044151992e554b0577?s=96&d=mm&r=g\",\"caption\":\"Ivo Giudicetti\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trasmessa al Consiglio federale la convenzione sulla qualit\u00e0 per l\u2019ergoterapia - Prio.Swiss \u2013 Der Verband Schweizer Krankenversicherer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prio.swiss\/it\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\/","og_locale":"it_IT","og_type":"article","og_title":"Trasmessa al Consiglio federale la convenzione sulla qualit\u00e0 per l\u2019ergoterapia - Prio.Swiss \u2013 Der Verband Schweizer Krankenversicherer","og_description":"L\u2019Associazione svizzera di ergoterapia, la Croce Rossa Svizzera e l\u2019Associazione degli assicuratori-malattia svizzeri prio.swiss hanno presentato oggi al Consiglio federale la convenzione sulla qualit\u00e0 tra ergoterapisti e assicuratori malattia.","og_url":"https:\/\/prio.swiss\/it\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\/","og_site_name":"Prio.Swiss \u2013 Der Verband Schweizer Krankenversicherer","article_published_time":"2025-11-27T13:09:16+00:00","article_modified_time":"2025-11-28T08:21:16+00:00","author":"Ivo Giudicetti","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Ivo Giudicetti","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prio.swiss\/it\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\/#article","isPartOf":{"@id":"https:\/\/prio.swiss\/it\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\/"},"author":{"name":"Ivo Giudicetti","@id":"https:\/\/prio.swiss\/#\/schema\/person\/4d9497c27b718f03a1e874527475adea"},"headline":"Trasmessa al Consiglio federale la convenzione sulla qualit\u00e0 per l\u2019ergoterapia","datePublished":"2025-11-27T13:09:16+00:00","dateModified":"2025-11-28T08:21:16+00:00","mainEntityOfPage":{"@id":"https:\/\/prio.swiss\/it\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\/"},"wordCount":388,"articleSection":["Comunicati"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/prio.swiss\/it\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\/","url":"https:\/\/prio.swiss\/it\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\/","name":"Trasmessa al Consiglio federale la convenzione sulla qualit\u00e0 per l\u2019ergoterapia - Prio.Swiss \u2013 Der Verband Schweizer Krankenversicherer","isPartOf":{"@id":"https:\/\/prio.swiss\/#website"},"datePublished":"2025-11-27T13:09:16+00:00","dateModified":"2025-11-28T08:21:16+00:00","author":{"@id":"https:\/\/prio.swiss\/#\/schema\/person\/4d9497c27b718f03a1e874527475adea"},"breadcrumb":{"@id":"https:\/\/prio.swiss\/it\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prio.swiss\/it\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/prio.swiss\/it\/trasmessa-al-consiglio-federale-la-convenzione-sulla-qualita-per-lergoterapia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/prio.swiss\/it\/"},{"@type":"ListItem","position":2,"name":"Trasmessa al Consiglio federale la convenzione sulla qualit\u00e0 per l\u2019ergoterapia"}]},{"@type":"WebSite","@id":"https:\/\/prio.swiss\/#website","url":"https:\/\/prio.swiss\/","name":"Prio.Swiss \u2013 Der Verband Schweizer Krankenversicherer","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prio.swiss\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/prio.swiss\/#\/schema\/person\/4d9497c27b718f03a1e874527475adea","name":"Ivo Giudicetti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a9556a66894283924e2a939c86ab0cdd52d95066a830df044151992e554b0577?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a9556a66894283924e2a939c86ab0cdd52d95066a830df044151992e554b0577?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a9556a66894283924e2a939c86ab0cdd52d95066a830df044151992e554b0577?s=96&d=mm&r=g","caption":"Ivo Giudicetti"}}]}},"_links":{"self":[{"href":"https:\/\/prio.swiss\/it\/wp-json\/wp\/v2\/posts\/4837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prio.swiss\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prio.swiss\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prio.swiss\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/prio.swiss\/it\/wp-json\/wp\/v2\/comments?post=4837"}],"version-history":[{"count":1,"href":"https:\/\/prio.swiss\/it\/wp-json\/wp\/v2\/posts\/4837\/revisions"}],"predecessor-version":[{"id":4841,"href":"https:\/\/prio.swiss\/it\/wp-json\/wp\/v2\/posts\/4837\/revisions\/4841"}],"wp:attachment":[{"href":"https:\/\/prio.swiss\/it\/wp-json\/wp\/v2\/media?parent=4837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prio.swiss\/it\/wp-json\/wp\/v2\/categories?post=4837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prio.swiss\/it\/wp-json\/wp\/v2\/tags?post=4837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}